{"id":8878,"date":"2022-01-17T15:39:04","date_gmt":"2022-01-17T14:39:04","guid":{"rendered":"https:\/\/lesateliersduvisage.fr\/?page_id=8878"},"modified":"2026-02-26T15:48:58","modified_gmt":"2026-02-26T14:48:58","slug":"the-tip","status":"publish","type":"page","link":"https:\/\/lesateliersduvisage.fr\/en\/rhinoplasty\/the-tip\/","title":{"rendered":"The tip"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<div class=\"grid-video opero-formations-container\" id=\"opero-formations-6a57296ac053b\" data-page=\"1\" data-items-per-page=\"9\" data-category=\"la-pointe\" data-tag-uuids='[&quot;33486ee0-5695-4e29-b223-4445b8f8707b&quot;,&quot;7f7a290f-9c96-4e2d-a40e-b3b4a1a25fe7&quot;]' data-not-tag-uuids='' data-featured-uuids='' data-random-seed=\"749769\" data-total-items=\"7\" data-search-text=\"\" data-loading=\"false\">    <a href=\"https:\/\/lesateliersduvisage.opero.tv\/app\/cours\/58e39da4-ef87-44f5-a3bc-598965a42082\/modules?lang=en\" target=\"_blank\">\r\n        <div class=\"bloc_video w-100\" style=\"background-image:url(https://spcdn.shortpixel.ai/spio/ret_img,q_cdnize,to_webp,s_webp/lesateliersduvisage.fr/wp-content/uploads/2026/02/AdV_vignettes-videos-660x440px-Rhinoplastie.jpg)\">\r\n            <div class=\"row\">\r\n                <div>\r\n                    <h2 class=\"video_name\">The lateral crural overlay: deprojection and cephalic rotati\u2026<\/h2>\r\n                                            <p class=\"doctor\">Pr Thomas Radulesco<\/p>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/a>\r\n        <a href=\"https:\/\/lesateliersduvisage.opero.tv\/app\/cours\/4526bec8-0969-4c61-99cc-990d3449abc3\/modules?lang=en\" target=\"_blank\">\r\n        <div class=\"bloc_video w-100\" style=\"background-image:url(https://spcdn.shortpixel.ai/spio/ret_img,q_cdnize,to_webp,s_webp/lesateliersduvisage.fr/wp-content/uploads/2026/02/AdV_vignettes-videos-660x440px-Rhinoplastie.jpg)\">\r\n            <div class=\"row\">\r\n                <div>\r\n                    <h2 class=\"video_name\">Drooping tips in rhinoplasty: alolateropexy<\/h2>\r\n                                            <p class=\"doctor\">Pr Justin Michel<\/p>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/a>\r\n        <a href=\"https:\/\/lesateliersduvisage.opero.tv\/app\/cours\/eb3c6425-4ac3-4131-b438-8f8c48938a90\/modules?lang=en\" target=\"_blank\">\r\n        <div class=\"bloc_video w-100\" style=\"background-image:url(https://spcdn.shortpixel.ai/spio/ret_img,q_cdnize,to_webp,s_webp/lesateliersduvisage.fr/wp-content/uploads/2026/02/AdV_vignettes-videos-660x440px-Rhinoplastie.jpg)\">\r\n            <div class=\"row\">\r\n                <div>\r\n                    <h2 class=\"video_name\">Sliding alar cartilage flap (commented video)<\/h2>\r\n                                            <p class=\"doctor\">Pr Thomas Radulesco<\/p>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/a>\r\n        <a href=\"https:\/\/lesateliersduvisage.opero.tv\/app\/cours\/57ea91e6-afa1-4ed8-be3c-a393b6e75419\/modules?lang=en\" target=\"_blank\">\r\n        <div class=\"bloc_video w-100\" style=\"background-image:url(https://spcdn.shortpixel.ai/spio/ret_img,q_cdnize,to_webp,s_webp/lesateliersduvisage.fr/wp-content/uploads/2026/02/AdV_vignettes-videos-660x440px-Rhinoplastie.jpg)\">\r\n            <div class=\"row\">\r\n                <div>\r\n                    <h2 class=\"video_name\">Management of a hyperprojected nose through a concealed appr\u2026<\/h2>\r\n                                            <p class=\"doctor\">Pr Thomas Radulesco<\/p>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/a>\r\n        <a href=\"https:\/\/lesateliersduvisage.opero.tv\/app\/cours\/8c173832-bbf6-4d60-a05d-b714d40e310f\/modules?lang=en\" target=\"_blank\">\r\n        <div class=\"bloc_video w-100\" style=\"background-image:url(https://spcdn.shortpixel.ai/spio/ret_img,q_cdnize,to_webp,s_webp/lesateliersduvisage.fr/wp-content/uploads/2026/02/AdV_vignettes-videos-660x440px-Rhinoplastie.jpg)\">\r\n            <div class=\"row\">\r\n                <div>\r\n                    <h2 class=\"video_name\">The rib graft in rhinoplasty<\/h2>\r\n                                            <p class=\"doctor\">Pr Thomas Radulesco<\/p>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/a>\r\n        <a href=\"https:\/\/lesateliersduvisage.opero.tv\/app\/cours\/5299c39a-5f0b-40d4-b45d-345d98385c0d\/modules?lang=en\" target=\"_blank\">\r\n        <div class=\"bloc_video w-100\" style=\"background-image:url(https://spcdn.shortpixel.ai/spio/ret_img,q_cdnize,to_webp,s_webp/lesateliersduvisage.fr/wp-content/uploads/2026/02/AdV_vignettes-videos-660x440px-Rhinoplastie.jpg)\">\r\n            <div class=\"row\">\r\n                <div>\r\n                    <h2 class=\"video_name\">Defining the tip of the nose<\/h2>\r\n                                            <p class=\"doctor\">Pr Guillaume De Bonnecaze<\/p>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/a>\r\n        <a href=\"https:\/\/lesateliersduvisage.opero.tv\/app\/cours\/2e2fda4d-6426-440a-b0c9-5c41b246b262\/modules?lang=en\" target=\"_blank\">\r\n        <div class=\"bloc_video w-100\" style=\"background-image:url(https://spcdn.shortpixel.ai/spio/ret_img,q_cdnize,to_webp,s_webp/lesateliersduvisage.fr/wp-content/uploads/2026/02/AdV_vignettes-videos-660x440px-Rhinoplastie.jpg)\">\r\n            <div class=\"row\">\r\n                <div>\r\n                    <h2 class=\"video_name\">How to raise the tip of the nose: the lateral crural steal (\u2026<\/h2>\r\n                                            <p class=\"doctor\">Pr Thomas Radulesco<\/p>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/a>\r\n    <\/div>        <div class=\"opero-loader\" style=\"display: none; text-align: center; padding: 20px;\">\r\n            <div style=\"display: inline-block; width: 40px; height: 40px; border: 4px solid #f3f3f3; border-top: 4px solid #3498db; border-radius: 50%; animation: spin 1s linear infinite;\"><\/div>\r\n            <p>Loading...<\/p>\r\n        <\/div>\r\n        <div class=\"opero-load-more-btn-container\" style=\"text-align: center; padding: 30px 20px;\">\r\n            <button type=\"button\" class=\"opero-load-more-btn\"\r\n                data-text-default=\"See more training courses\"\r\n                data-text-loading=\"Loading...\"\r\n                style=\"padding: 14px 40px; font-size: 16px; font-weight: 600; background-color: #0073aa; color: white; border: 2px solid #0073aa; border-radius: 50px; cursor: pointer; transition: all 0.3s; box-shadow: 0 2px 8px rgba(0,115,170,0.2);\" onmouseover=\"this.style.backgroundColor='white'; this.style.color='#0073aa';\" onmouseout=\"this.style.backgroundColor='#0073aa'; this.style.color='white';\">\r\n                See more training courses            <\/button>\r\n        <\/div>\r\n        <style>\r\n            @keyframes spin {\r\n                0% { transform: rotate(0deg); }\r\n                100% { transform: rotate(360deg); }\r\n            }\r\n        <\/style>\r\n        [\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":2503,"featured_media":0,"parent":7197,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-fullwidth.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-8878","page","type-page","status-publish","hentry","odd"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The tip - Les Ateliers du Visage<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lesateliersduvisage.fr\/en\/rhinoplasty\/the-tip\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The tip - Les Ateliers du Visage\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text css=&#8221;&#8221;][\/vc_column_text][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lesateliersduvisage.fr\/en\/rhinoplasty\/the-tip\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Ateliers du Visage\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T14:48:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/rhinoplasty\\\/the-tip\\\/\",\"url\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/rhinoplasty\\\/the-tip\\\/\",\"name\":\"The tip - Les Ateliers du Visage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/#website\"},\"datePublished\":\"2022-01-17T14:39:04+00:00\",\"dateModified\":\"2026-02-26T14:48:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/rhinoplasty\\\/the-tip\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/rhinoplasty\\\/the-tip\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/rhinoplasty\\\/the-tip\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rhinoplasty\",\"item\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/rhinoplasty\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The tip\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/\",\"name\":\"Les Ateliers du Visage\",\"description\":\"Site de formation chirurgicale\",\"publisher\":{\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/#organization\",\"name\":\"Les Ateliers du Visage\",\"url\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/adv-logo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/adv-logo-2.jpg\",\"width\":1000,\"height\":369,\"caption\":\"Les Ateliers du Visage\"},\"image\":{\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The tip - Les Ateliers du Visage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lesateliersduvisage.fr\/en\/rhinoplasty\/the-tip\/","og_locale":"en_US","og_type":"article","og_title":"The tip - Les Ateliers du Visage","og_description":"[vc_row][vc_column][vc_column_text css=&#8221;&#8221;][\/vc_column_text][\/vc_column][\/vc_row]","og_url":"https:\/\/lesateliersduvisage.fr\/en\/rhinoplasty\/the-tip\/","og_site_name":"Les Ateliers du Visage","article_modified_time":"2026-02-26T14:48:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lesateliersduvisage.fr\/en\/rhinoplasty\/the-tip\/","url":"https:\/\/lesateliersduvisage.fr\/en\/rhinoplasty\/the-tip\/","name":"The tip - Les Ateliers du Visage","isPartOf":{"@id":"https:\/\/lesateliersduvisage.fr\/en\/#website"},"datePublished":"2022-01-17T14:39:04+00:00","dateModified":"2026-02-26T14:48:58+00:00","breadcrumb":{"@id":"https:\/\/lesateliersduvisage.fr\/en\/rhinoplasty\/the-tip\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lesateliersduvisage.fr\/en\/rhinoplasty\/the-tip\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lesateliersduvisage.fr\/en\/rhinoplasty\/the-tip\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lesateliersduvisage.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Rhinoplasty","item":"https:\/\/lesateliersduvisage.fr\/en\/rhinoplasty\/"},{"@type":"ListItem","position":3,"name":"The tip"}]},{"@type":"WebSite","@id":"https:\/\/lesateliersduvisage.fr\/en\/#website","url":"https:\/\/lesateliersduvisage.fr\/en\/","name":"Les Ateliers du Visage","description":"Site de formation chirurgicale","publisher":{"@id":"https:\/\/lesateliersduvisage.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lesateliersduvisage.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lesateliersduvisage.fr\/en\/#organization","name":"Les Ateliers du Visage","url":"https:\/\/lesateliersduvisage.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lesateliersduvisage.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/lesateliersduvisage.fr\/wp-content\/uploads\/2025\/12\/adv-logo-2.jpg","contentUrl":"https:\/\/lesateliersduvisage.fr\/wp-content\/uploads\/2025\/12\/adv-logo-2.jpg","width":1000,"height":369,"caption":"Les Ateliers du Visage"},"image":{"@id":"https:\/\/lesateliersduvisage.fr\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lesateliersduvisage.fr\/en\/wp-json\/wp\/v2\/pages\/8878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesateliersduvisage.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lesateliersduvisage.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lesateliersduvisage.fr\/en\/wp-json\/wp\/v2\/users\/2503"}],"replies":[{"embeddable":true,"href":"https:\/\/lesateliersduvisage.fr\/en\/wp-json\/wp\/v2\/comments?post=8878"}],"version-history":[{"count":2,"href":"https:\/\/lesateliersduvisage.fr\/en\/wp-json\/wp\/v2\/pages\/8878\/revisions"}],"predecessor-version":[{"id":9366,"href":"https:\/\/lesateliersduvisage.fr\/en\/wp-json\/wp\/v2\/pages\/8878\/revisions\/9366"}],"up":[{"embeddable":true,"href":"https:\/\/lesateliersduvisage.fr\/en\/wp-json\/wp\/v2\/pages\/7197"}],"wp:attachment":[{"href":"https:\/\/lesateliersduvisage.fr\/en\/wp-json\/wp\/v2\/media?parent=8878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}