{"id":644,"count":0,"description":"","link":"https:\/\/lesateliersduvisage.fr\/en\/category\/articles\/aesthetic-medicine\/","name":"Aesthetic medicine","slug":"aesthetic-medicine","taxonomy":"category","parent":602,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Aesthetic medicine - Les Ateliers du Visage<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lesateliersduvisage.fr\/en\/category\/articles\/aesthetic-medicine\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Aesthetic medicine - Les Ateliers du Visage\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lesateliersduvisage.fr\/en\/category\/articles\/aesthetic-medicine\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Ateliers du Visage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/category\\\/articles\\\/aesthetic-medicine\\\/\",\"url\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/category\\\/articles\\\/aesthetic-medicine\\\/\",\"name\":\"Archives des Aesthetic medicine - Les Ateliers du Visage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/category\\\/articles\\\/aesthetic-medicine\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/category\\\/articles\\\/aesthetic-medicine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/category\\\/articles\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aesthetic medicine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/\",\"name\":\"Les Ateliers du Visage\",\"description\":\"Site de formation chirurgicale\",\"publisher\":{\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/#organization\",\"name\":\"Les Ateliers du Visage\",\"url\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/adv-logo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/adv-logo-2.jpg\",\"width\":1000,\"height\":369,\"caption\":\"Les Ateliers du Visage\"},\"image\":{\"@id\":\"https:\\\/\\\/lesateliersduvisage.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Aesthetic medicine - Les Ateliers du Visage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lesateliersduvisage.fr\/en\/category\/articles\/aesthetic-medicine\/","og_locale":"en_US","og_type":"article","og_title":"Archives des Aesthetic medicine - Les Ateliers du Visage","og_url":"https:\/\/lesateliersduvisage.fr\/en\/category\/articles\/aesthetic-medicine\/","og_site_name":"Les Ateliers du Visage","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lesateliersduvisage.fr\/en\/category\/articles\/aesthetic-medicine\/","url":"https:\/\/lesateliersduvisage.fr\/en\/category\/articles\/aesthetic-medicine\/","name":"Archives des Aesthetic medicine - Les Ateliers du Visage","isPartOf":{"@id":"https:\/\/lesateliersduvisage.fr\/en\/#website"},"breadcrumb":{"@id":"https:\/\/lesateliersduvisage.fr\/en\/category\/articles\/aesthetic-medicine\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/lesateliersduvisage.fr\/en\/category\/articles\/aesthetic-medicine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lesateliersduvisage.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/lesateliersduvisage.fr\/en\/category\/articles\/"},{"@type":"ListItem","position":3,"name":"Aesthetic medicine"}]},{"@type":"WebSite","@id":"https:\/\/lesateliersduvisage.fr\/en\/#website","url":"https:\/\/lesateliersduvisage.fr\/en\/","name":"Les Ateliers du Visage","description":"Site de formation chirurgicale","publisher":{"@id":"https:\/\/lesateliersduvisage.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lesateliersduvisage.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lesateliersduvisage.fr\/en\/#organization","name":"Les Ateliers du Visage","url":"https:\/\/lesateliersduvisage.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lesateliersduvisage.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/lesateliersduvisage.fr\/wp-content\/uploads\/2025\/12\/adv-logo-2.jpg","contentUrl":"https:\/\/lesateliersduvisage.fr\/wp-content\/uploads\/2025\/12\/adv-logo-2.jpg","width":1000,"height":369,"caption":"Les Ateliers du Visage"},"image":{"@id":"https:\/\/lesateliersduvisage.fr\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lesateliersduvisage.fr\/en\/wp-json\/wp\/v2\/categories\/644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesateliersduvisage.fr\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lesateliersduvisage.fr\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/lesateliersduvisage.fr\/en\/wp-json\/wp\/v2\/categories\/602"}],"wp:post_type":[{"href":"https:\/\/lesateliersduvisage.fr\/en\/wp-json\/wp\/v2\/posts?categories=644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}